{"id":8082,"date":"2022-10-13T12:48:21","date_gmt":"2022-10-13T17:48:21","guid":{"rendered":"http:\/\/aquadepotinc.com\/?post_type=product&#038;p=8082"},"modified":"2023-08-18T10:03:10","modified_gmt":"2023-08-18T16:03:10","slug":"desnatadores-sibrape-mini","status":"publish","type":"product","link":"https:\/\/aquadepotinc.com\/en\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/","title":{"rendered":"RETRO Skimmers Sibrape"},"content":{"rendered":"<p>Skimmers<\/p>","protected":false},"excerpt":{"rendered":"<p>Skimmers<\/p>","protected":false},"featured_media":8090,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[1483,1369,223],"product_tag":[1479,1480,111],"class_list":["post-8082","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios-empotrables","product_cat-piscinas-y-quimicos","product_cat-empotrables","product_tag-desnatador","product_tag-skimmer","product_tag-sibrape","pa_marca-sibrape","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desnatadores RETO Sibrape - AquaDepot, Inc.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquadepotinc.com\/en\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desnatadores RETO Sibrape - AquaDepot, Inc.\" \/>\n<meta property=\"og:description\" content=\"Desnatadores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquadepotinc.com\/en\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/\" \/>\n<meta property=\"og:site_name\" content=\"AquaDepot, Inc.\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-18T16:03:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquadepotinc.com\/wp-content\/uploads\/MicrosoftTeams-image-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3085\" \/>\n\t<meta property=\"og:image:height\" content=\"3085\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/\",\"url\":\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/\",\"name\":\"Desnatadores RETO Sibrape - AquaDepot, Inc.\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aquadepotinc.com\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-3.png\",\"datePublished\":\"2022-10-13T17:48:21+00:00\",\"dateModified\":\"2023-08-18T16:03:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aquadepotinc.com\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-3.png\",\"contentUrl\":\"https:\\\/\\\/aquadepotinc.com\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-3.png\",\"width\":3085,\"height\":3085},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquadepotinc.com\\\/productos\\\/piscinas-y-quimicos\\\/empotrables\\\/desnatadores-sibrape-mini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aquadepotinc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desnatadores RETO Sibrape\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"AquaDepot, Inc.\",\"description\":\"Distribuidora Mayorista Exportadora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desnatadores RETO Sibrape - AquaDepot, Inc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquadepotinc.com\/en\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/","og_locale":"en_US","og_type":"article","og_title":"Desnatadores RETO Sibrape - AquaDepot, Inc.","og_description":"Desnatadores","og_url":"https:\/\/aquadepotinc.com\/en\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/","og_site_name":"AquaDepot, Inc.","article_modified_time":"2023-08-18T16:03:10+00:00","og_image":[{"width":3085,"height":3085,"url":"https:\/\/aquadepotinc.com\/wp-content\/uploads\/MicrosoftTeams-image-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/","url":"https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/","name":"Desnatadores RETO Sibrape - AquaDepot, Inc.","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/#primaryimage"},"image":{"@id":"https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/#primaryimage"},"thumbnailUrl":"https:\/\/aquadepotinc.com\/wp-content\/uploads\/MicrosoftTeams-image-3.png","datePublished":"2022-10-13T17:48:21+00:00","dateModified":"2023-08-18T16:03:10+00:00","breadcrumb":{"@id":"https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/#primaryimage","url":"https:\/\/aquadepotinc.com\/wp-content\/uploads\/MicrosoftTeams-image-3.png","contentUrl":"https:\/\/aquadepotinc.com\/wp-content\/uploads\/MicrosoftTeams-image-3.png","width":3085,"height":3085},{"@type":"BreadcrumbList","@id":"https:\/\/aquadepotinc.com\/productos\/piscinas-y-quimicos\/empotrables\/desnatadores-sibrape-mini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquadepotinc.com\/"},{"@type":"ListItem","position":2,"name":"Desnatadores RETO Sibrape"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"AquaDepot, Inc.","description":"Distribuidora Mayorista Exportadora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/product\/8082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/media\/8090"}],"wp:attachment":[{"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/media?parent=8082"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/product_brand?post=8082"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/product_cat?post=8082"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aquadepotinc.com\/en\/wp-json\/wp\/v2\/product_tag?post=8082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}